{"id":31823,"date":"2024-10-08T19:47:18","date_gmt":"2024-10-08T17:47:18","guid":{"rendered":"https:\/\/mail.originalcyclingjerseys.com\/?post_type=product&#038;p=31823"},"modified":"2026-05-13T15:36:37","modified_gmt":"2026-05-13T13:36:37","slug":"aa-drinks-leontien-nl-222","status":"publish","type":"product","link":"https:\/\/mail.originalcyclingjerseys.com\/de\/retro-wielershirt\/quickstep-p-soudal-2024-wielershirt\/","title":{"rendered":"QUICKSTEP (p)-SOUDAL 2024 RADFAHREN-HEMD"},"content":{"rendered":"<p>QUICKSTEP-SOUDAL 2024<\/p>","protected":false},"excerpt":{"rendered":"<p>QUICKSTEP-SOUDAL 2024<\/p>","protected":false},"featured_media":31833,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-31823","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","outofstock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>QUICKSTEP (p)-SOUDAL 2024   WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.replica-cycling.com\/de\/retro-radtrikot\/aa-drinks-leontien-nl-222\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"QUICKSTEP (p)-SOUDAL 2024   WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:description\" content=\"QUICKSTEP-SOUDAL 2024\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.replica-cycling.com\/de\/retro-radtrikot\/aa-drinks-leontien-nl-222\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:36:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2024\/10\/IMG_3168-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-radtrikot\\\/aa-drinks-leontien-nl-222\\\/\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-radtrikot\\\/aa-drinks-leontien-nl-222\\\/\",\"name\":\"QUICKSTEP (p)-SOUDAL 2024 WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-radtrikot\\\/aa-drinks-leontien-nl-222\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-radtrikot\\\/aa-drinks-leontien-nl-222\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/IMG_3168-scaled.jpg\",\"datePublished\":\"2024-10-08T17:47:18+00:00\",\"dateModified\":\"2026-05-13T13:36:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-radtrikot\\\/aa-drinks-leontien-nl-222\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-radtrikot\\\/aa-drinks-leontien-nl-222\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-radtrikot\\\/aa-drinks-leontien-nl-222\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/IMG_3168-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/IMG_3168-scaled.jpg\",\"width\":1920,\"height\":2560,\"caption\":\"QUICKSTEP-SOUDAL 2024\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-radtrikot\\\/aa-drinks-leontien-nl-222\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"QUICKSTEP (p)-SOUDAL 2024 WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"QUICKSTEP (p)-SOUDAL 2024 RADTRIKOT - Ton Merckx Radtrikots - Tour durch die Welt der Radtrikots","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.replica-cycling.com\/de\/retro-radtrikot\/aa-drinks-leontien-nl-222\/","og_locale":"de_DE","og_type":"article","og_title":"QUICKSTEP (p)-SOUDAL 2024   WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_description":"QUICKSTEP-SOUDAL 2024","og_url":"https:\/\/mail.replica-cycling.com\/de\/retro-radtrikot\/aa-drinks-leontien-nl-222\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-05-13T13:36:37+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2024\/10\/IMG_3168-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.replica-cycling.com\/de\/retro-radtrikot\/aa-drinks-leontien-nl-222\/","url":"https:\/\/mail.replica-cycling.com\/de\/retro-radtrikot\/aa-drinks-leontien-nl-222\/","name":"QUICKSTEP (p)-SOUDAL 2024 RADTRIKOT - Ton Merckx Radtrikots - Tour durch die Welt der Radtrikots","isPartOf":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.replica-cycling.com\/de\/retro-radtrikot\/aa-drinks-leontien-nl-222\/#primaryimage"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/de\/retro-radtrikot\/aa-drinks-leontien-nl-222\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.originalcyclingjerseys.com\/wp-content\/uploads\/2024\/10\/IMG_3168-scaled.jpg","datePublished":"2024-10-08T17:47:18+00:00","dateModified":"2026-05-13T13:36:37+00:00","breadcrumb":{"@id":"https:\/\/mail.replica-cycling.com\/de\/retro-radtrikot\/aa-drinks-leontien-nl-222\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.replica-cycling.com\/de\/retro-radtrikot\/aa-drinks-leontien-nl-222\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mail.replica-cycling.com\/de\/retro-radtrikot\/aa-drinks-leontien-nl-222\/#primaryimage","url":"https:\/\/mail.originalcyclingjerseys.com\/wp-content\/uploads\/2024\/10\/IMG_3168-scaled.jpg","contentUrl":"https:\/\/mail.originalcyclingjerseys.com\/wp-content\/uploads\/2024\/10\/IMG_3168-scaled.jpg","width":1920,"height":2560,"caption":"QUICKSTEP-SOUDAL 2024"},{"@type":"BreadcrumbList","@id":"https:\/\/mail.replica-cycling.com\/de\/retro-radtrikot\/aa-drinks-leontien-nl-222\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"QUICKSTEP (p)-SOUDAL 2024 WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.cycling-originals.com\/pt\/#website","url":"https:\/\/mail.cycling-originals.com\/pt\/","name":"Ton Merckx Radsport-Shirts \u2013 Tour durch die Welt der Radsport-Shirts","description":"Tausende originale Radtrikots \u2013 bestellen Sie Ihr Replikat!","publisher":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.cycling-originals.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization","name":"Ton Merckx Radsport-Shirts \u2013 Tour durch die Welt der Radsport-Shirts","url":"https:\/\/mail.cycling-originals.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/mail.originalcyclingjerseys.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.originalcyclingjerseys.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.originalcyclingjerseys.com\/de\/wp-json\/wp\/v2\/product\/31823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.originalcyclingjerseys.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.originalcyclingjerseys.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.originalcyclingjerseys.com\/de\/wp-json\/wp\/v2\/media\/31833"}],"wp:attachment":[{"href":"https:\/\/mail.originalcyclingjerseys.com\/de\/wp-json\/wp\/v2\/media?parent=31823"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.originalcyclingjerseys.com\/de\/wp-json\/wp\/v2\/product_brand?post=31823"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.originalcyclingjerseys.com\/de\/wp-json\/wp\/v2\/product_cat?post=31823"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.originalcyclingjerseys.com\/de\/wp-json\/wp\/v2\/product_tag?post=31823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}