{"id":717,"date":"2023-01-24T17:29:50","date_gmt":"2023-01-24T17:29:50","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/algemeen-klassement-23\/"},"modified":"2026-05-13T15:40:06","modified_gmt":"2026-05-13T13:40:06","slug":"classement-general-23","status":"publish","type":"product","link":"https:\/\/mail.originalcyclingjerseys.com\/fr\/retro-wielershirt\/algemeen-klassement-23\/","title":{"rendered":"GIRO DEL CAPO \u2013 CLASSIFICATION G\u00c9N\u00c9RALE \u2013 1992 \u2013 MAILLOT DE CYCLISME"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":716,"template":"","meta":[],"product_brand":[],"product_cat":[54],"product_tag":[],"class_list":["post-717","product","type-product","status-publish","has-post-thumbnail","product_cat-leiderstruien","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GIRO DEL CAPO - ALGEMEEN KLASSEMENT - 1992 - WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.originalcyclingjerseys.com\/fr\/maillot-de-cyclisme-retro\/classement-general-23\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GIRO DEL CAPO - ALGEMEEN KLASSEMENT - 1992 - WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.originalcyclingjerseys.com\/fr\/maillot-de-cyclisme-retro\/classement-general-23\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:40:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.originalcyclingjerseys.com\/wp-content\/uploads\/2023\/01\/SSA44051.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1704\" \/>\n\t<meta property=\"og:image:height\" content=\"2272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/it\\\/maglia-da-ciclismo-retro\\\/classificazione-generale-23\\\/\",\"url\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/it\\\/maglia-da-ciclismo-retro\\\/classificazione-generale-23\\\/\",\"name\":\"GIRO DEL CAPO - ALGEMEEN KLASSEMENT - 1992 - WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/it\\\/maglia-da-ciclismo-retro\\\/classificazione-generale-23\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/it\\\/maglia-da-ciclismo-retro\\\/classificazione-generale-23\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA44051.jpg\",\"datePublished\":\"2023-01-24T17:29:50+00:00\",\"dateModified\":\"2026-05-13T13:40:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/it\\\/maglia-da-ciclismo-retro\\\/classificazione-generale-23\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/it\\\/maglia-da-ciclismo-retro\\\/classificazione-generale-23\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/it\\\/maglia-da-ciclismo-retro\\\/classificazione-generale-23\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA44051.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA44051.jpg\",\"width\":1704,\"height\":2272},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/it\\\/maglia-da-ciclismo-retro\\\/classificazione-generale-23\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"GIRO DEL CAPO &#8211; ALGEMEEN KLASSEMENT &#8211; 1992 &#8211; WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GIRO DEL CAPO - CLASSIFICATION G\u00c9N\u00c9RALE - 1992 - MAILLOT DE CYCLISME - Maillots de cyclisme Ton Merckx - Tour \u00e0 travers le monde des maillots de cyclisme","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.originalcyclingjerseys.com\/fr\/maillot-de-cyclisme-retro\/classement-general-23\/","og_locale":"fr_FR","og_type":"article","og_title":"GIRO DEL CAPO - ALGEMEEN KLASSEMENT - 1992 - WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_url":"https:\/\/mail.originalcyclingjerseys.com\/fr\/maillot-de-cyclisme-retro\/classement-general-23\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-05-13T13:40:06+00:00","og_image":[{"width":1704,"height":2272,"url":"https:\/\/mail.originalcyclingjerseys.com\/wp-content\/uploads\/2023\/01\/SSA44051.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.originalcyclingjerseys.com\/it\/maglia-da-ciclismo-retro\/classificazione-generale-23\/","url":"https:\/\/mail.originalcyclingjerseys.com\/it\/maglia-da-ciclismo-retro\/classificazione-generale-23\/","name":"GIRO DEL CAPO - CLASSIFICATION G\u00c9N\u00c9RALE - 1992 - MAILLOT DE CYCLISME - Maillots de cyclisme Ton Merckx - Tour \u00e0 travers le monde des maillots de cyclisme","isPartOf":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.originalcyclingjerseys.com\/it\/maglia-da-ciclismo-retro\/classificazione-generale-23\/#primaryimage"},"image":{"@id":"https:\/\/mail.originalcyclingjerseys.com\/it\/maglia-da-ciclismo-retro\/classificazione-generale-23\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.originalcyclingjerseys.com\/wp-content\/uploads\/2023\/01\/SSA44051.jpg","datePublished":"2023-01-24T17:29:50+00:00","dateModified":"2026-05-13T13:40:06+00:00","breadcrumb":{"@id":"https:\/\/mail.originalcyclingjerseys.com\/it\/maglia-da-ciclismo-retro\/classificazione-generale-23\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.originalcyclingjerseys.com\/it\/maglia-da-ciclismo-retro\/classificazione-generale-23\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mail.originalcyclingjerseys.com\/it\/maglia-da-ciclismo-retro\/classificazione-generale-23\/#primaryimage","url":"https:\/\/mail.originalcyclingjerseys.com\/wp-content\/uploads\/2023\/01\/SSA44051.jpg","contentUrl":"https:\/\/mail.originalcyclingjerseys.com\/wp-content\/uploads\/2023\/01\/SSA44051.jpg","width":1704,"height":2272},{"@type":"BreadcrumbList","@id":"https:\/\/mail.originalcyclingjerseys.com\/it\/maglia-da-ciclismo-retro\/classificazione-generale-23\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"GIRO DEL CAPO &#8211; ALGEMEEN KLASSEMENT &#8211; 1992 &#8211; WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.cycling-originals.com\/pt\/#website","url":"https:\/\/mail.cycling-originals.com\/pt\/","name":"Chemises de cyclisme Ton Merckx - Tour \u00e0 travers le monde des chemises de cyclisme","description":"des milliers de maillots de cyclisme originaux - commandez votre r\u00e9plique !","publisher":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.cycling-originals.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization","name":"Chemises de cyclisme Ton Merckx - Tour \u00e0 travers le monde des chemises de cyclisme","url":"https:\/\/mail.cycling-originals.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/mail.originalcyclingjerseys.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.originalcyclingjerseys.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.originalcyclingjerseys.com\/fr\/wp-json\/wp\/v2\/product\/717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.originalcyclingjerseys.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.originalcyclingjerseys.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.originalcyclingjerseys.com\/fr\/wp-json\/wp\/v2\/media\/716"}],"wp:attachment":[{"href":"https:\/\/mail.originalcyclingjerseys.com\/fr\/wp-json\/wp\/v2\/media?parent=717"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.originalcyclingjerseys.com\/fr\/wp-json\/wp\/v2\/product_brand?post=717"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.originalcyclingjerseys.com\/fr\/wp-json\/wp\/v2\/product_cat?post=717"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.originalcyclingjerseys.com\/fr\/wp-json\/wp\/v2\/product_tag?post=717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}