{"id":3665,"date":"2023-01-24T18:05:08","date_gmt":"2023-01-24T18:05:08","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/gazelle-campagnolo\/"},"modified":"2026-06-10T19:15:33","modified_gmt":"2026-06-10T17:15:33","slug":"gazzella-campagnolo","status":"publish","type":"product","link":"https:\/\/mail.originalcyclingjerseys.com\/it\/retro-wielershirt\/gazelle-campagnolo\/","title":{"rendered":"MAGLIA CICLISMO GAZELLE (d)-CAMPAGNOLO 1978"},"content":{"rendered":"<p><strong>GAZELLE-CAMPAGNOLO 1978 <\/strong><\/p>\n<p><strong>Gazelle-Campagnolo<\/strong> La squadra del 1978 era una formazione improvvisata composta da diversi dilettanti, alcuni giovani corridori e persino donne. Si aggiunsero due professionisti: Ren\u00e9 Pijnen (lo specialista della Sei Giorni) e Toine Van De Bunder, che nel 1978 conquist\u00f2 praticamente tutte le vittorie per la Gazelle Campagnolo.<\/p>\n<ul>\n<li>24-01-1978 NED Rotterdam, Sei Giorni: Ren\u00e9 Pijnen<\/li>\n<li>03-05-1978 BEL Maldegem: Toine Van De Bunder<\/li>\n<li>12-03-1978 BEL Deinze, Dilettanti: Toine Van De Bunder<\/li>\n<li>18-03-1978 NED L&#039;Aia: Toine Van De Bunder<\/li>\n<li>25-03-1978 BEL Zelzate, Dilettanti: Toine Van De Bunder<\/li>\n<li>26-03-1978 NED IJzendijke, Dilettanti: Toine Van De Bunder<\/li>\n<li>01-04-1978 NED Inferno del Mergelland: Toine Van De Bunder<\/li>\n<li>15-04-1978 NED filippino: Toine Van De Bunder<\/li>\n<li>23-04-1978 Campionato Provinciale NED Zelanda: Toine Van De Bunder<\/li>\n<\/ul>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-29167\" src=\"https:\/\/mail.originalcyclingjerseys.com\/wp-content\/uploads\/2023\/01\/Toine-Van-De-Bunder-Gazelle-Campagnola-1978-195x300.jpeg\" alt=\"Gazelle-Campagonla 1978 - Toine Van De Bunder\" width=\"195\" height=\"300\" srcset=\"https:\/\/mail.originalcyclingjerseys.com\/wp-content\/uploads\/2023\/01\/Toine-Van-De-Bunder-Gazelle-Campagnola-1978-195x300.jpeg 195w, https:\/\/mail.originalcyclingjerseys.com\/wp-content\/uploads\/2023\/01\/Toine-Van-De-Bunder-Gazelle-Campagnola-1978-8x12.jpeg 8w, https:\/\/mail.originalcyclingjerseys.com\/wp-content\/uploads\/2023\/01\/Toine-Van-De-Bunder-Gazelle-Campagnola-1978.jpeg 450w\" sizes=\"(max-width: 195px) 100vw, 195px\" \/><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>GAZELLE-CAMPAGNOLO 1978 Gazelle-Campagnolo uit 1978 was een gelegenheidsteam bestaande uit een aantal amateurs, een paar junior renners en zelfs dames. Er werden twee profs aan toegevoegd; Ren\u00e9 Pijnen (de Zesdaagse specialist) en Toine Van De Bunder die in 1978 vrijwel alle overwinningen voor Gazelle Campagnolo op zijn naam zette. 24-01-1978 NED Rotterdam, Zesdaagse : Ren\u00e9 [&hellip;]<\/p>\n","protected":false},"featured_media":188409,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-3665","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GAZELLE (d)-CAMPAGNOLO  1978  WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"description\" content=\"Retro wielershirt Gazelle-Campagnola 1978. Gazelle-Campagnola was een gelegenheidsteam bestaande uit een aantal amateurs, junior renners en zelfs dames en 2 profs; Ren\u00e9 Pijnen en Toine Van De Bunder.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.originalcyclingjerseys.com\/it\/maglia-da-ciclismo-retro\/gazzella-campagnolo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GAZELLE (d)-CAMPAGNOLO  1978  WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:description\" content=\"Retro wielershirt Gazelle-Campagnola 1978. Gazelle-Campagnola was een gelegenheidsteam bestaande uit een aantal amateurs, junior renners en zelfs dames en 2 profs; Ren\u00e9 Pijnen en Toine Van De Bunder.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.originalcyclingjerseys.com\/it\/maglia-da-ciclismo-retro\/gazzella-campagnolo\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-10T17:15:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.originalcyclingjerseys.com\/wp-content\/uploads\/2023\/01\/007-11-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/de\\\/retro-radtrikot\\\/gazelle-campagnolo\\\/\",\"url\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/de\\\/retro-radtrikot\\\/gazelle-campagnolo\\\/\",\"name\":\"GAZELLE (d)-CAMPAGNOLO 1978 WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/de\\\/retro-radtrikot\\\/gazelle-campagnolo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/de\\\/retro-radtrikot\\\/gazelle-campagnolo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/007-11-scaled.jpg\",\"datePublished\":\"2023-01-24T18:05:08+00:00\",\"dateModified\":\"2026-06-10T17:15:33+00:00\",\"description\":\"Retro wielershirt Gazelle-Campagnola 1978. Gazelle-Campagnola was een gelegenheidsteam bestaande uit een aantal amateurs, junior renners en zelfs dames en 2 profs; Ren\u00e9 Pijnen en Toine Van De Bunder.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/de\\\/retro-radtrikot\\\/gazelle-campagnolo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/de\\\/retro-radtrikot\\\/gazelle-campagnolo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/de\\\/retro-radtrikot\\\/gazelle-campagnolo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/007-11-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/007-11-scaled.jpg\",\"width\":1920,\"height\":2560,\"caption\":\"GAZELLE-CAMPAGNOLO 1978\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/de\\\/retro-radtrikot\\\/gazelle-campagnolo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"GAZELLE (d)-CAMPAGNOLO 1978 WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.originalcyclingjerseys.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MAGLIA CICLISMO GAZELLE (d)-CAMPAGNOLO 1978 - Maglie ciclismo Ton Merckx - Viaggio nel mondo delle maglie ciclismo","description":"Maglia storica ciclismo Gazelle-Campagnola 1978. La Gazelle-Campagnola era una squadra occasionale composta da numerosi dilettanti, corridori junior e anche femminili e 2 professionisti; Ren\u00e9 Pijnen e Toine Van De Bunder.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.originalcyclingjerseys.com\/it\/maglia-da-ciclismo-retro\/gazzella-campagnolo\/","og_locale":"it_IT","og_type":"article","og_title":"GAZELLE (d)-CAMPAGNOLO  1978  WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_description":"Retro wielershirt Gazelle-Campagnola 1978. Gazelle-Campagnola was een gelegenheidsteam bestaande uit een aantal amateurs, junior renners en zelfs dames en 2 profs; Ren\u00e9 Pijnen en Toine Van De Bunder.","og_url":"https:\/\/mail.originalcyclingjerseys.com\/it\/maglia-da-ciclismo-retro\/gazzella-campagnolo\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-06-10T17:15:33+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/mail.originalcyclingjerseys.com\/wp-content\/uploads\/2023\/01\/007-11-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.originalcyclingjerseys.com\/de\/retro-radtrikot\/gazelle-campagnolo\/","url":"https:\/\/mail.originalcyclingjerseys.com\/de\/retro-radtrikot\/gazelle-campagnolo\/","name":"MAGLIA CICLISMO GAZELLE (d)-CAMPAGNOLO 1978 - Maglie ciclismo Ton Merckx - Viaggio nel mondo delle maglie ciclismo","isPartOf":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.originalcyclingjerseys.com\/de\/retro-radtrikot\/gazelle-campagnolo\/#primaryimage"},"image":{"@id":"https:\/\/mail.originalcyclingjerseys.com\/de\/retro-radtrikot\/gazelle-campagnolo\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.originalcyclingjerseys.com\/wp-content\/uploads\/2023\/01\/007-11-scaled.jpg","datePublished":"2023-01-24T18:05:08+00:00","dateModified":"2026-06-10T17:15:33+00:00","description":"Maglia storica ciclismo Gazelle-Campagnola 1978. La Gazelle-Campagnola era una squadra occasionale composta da numerosi dilettanti, corridori junior e anche femminili e 2 professionisti; Ren\u00e9 Pijnen e Toine Van De Bunder.","breadcrumb":{"@id":"https:\/\/mail.originalcyclingjerseys.com\/de\/retro-radtrikot\/gazelle-campagnolo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.originalcyclingjerseys.com\/de\/retro-radtrikot\/gazelle-campagnolo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mail.originalcyclingjerseys.com\/de\/retro-radtrikot\/gazelle-campagnolo\/#primaryimage","url":"https:\/\/mail.originalcyclingjerseys.com\/wp-content\/uploads\/2023\/01\/007-11-scaled.jpg","contentUrl":"https:\/\/mail.originalcyclingjerseys.com\/wp-content\/uploads\/2023\/01\/007-11-scaled.jpg","width":1920,"height":2560,"caption":"GAZELLE-CAMPAGNOLO 1978"},{"@type":"BreadcrumbList","@id":"https:\/\/mail.originalcyclingjerseys.com\/de\/retro-radtrikot\/gazelle-campagnolo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tonmerckxwielershirts.nl\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/tonmerckxwielershirts.nl\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"GAZELLE (d)-CAMPAGNOLO 1978 WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.replica-cycling.com\/ja\/#website","url":"https:\/\/mail.replica-cycling.com\/ja\/","name":"Magliette da ciclismo Ton Merckx - Tour nel mondo delle magliette da ciclismo","description":"migliaia di maglie da ciclismo originali - ordina la tua replica!","publisher":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.replica-cycling.com\/ja\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization","name":"Magliette da ciclismo Ton Merckx - Tour nel mondo delle magliette da ciclismo","url":"https:\/\/mail.replica-cycling.com\/ja\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/","url":"https:\/\/mail.originalcyclingjerseys.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.originalcyclingjerseys.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.originalcyclingjerseys.com\/it\/wp-json\/wp\/v2\/product\/3665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.originalcyclingjerseys.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.originalcyclingjerseys.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.originalcyclingjerseys.com\/it\/wp-json\/wp\/v2\/media\/188409"}],"wp:attachment":[{"href":"https:\/\/mail.originalcyclingjerseys.com\/it\/wp-json\/wp\/v2\/media?parent=3665"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.originalcyclingjerseys.com\/it\/wp-json\/wp\/v2\/product_brand?post=3665"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.originalcyclingjerseys.com\/it\/wp-json\/wp\/v2\/product_cat?post=3665"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.originalcyclingjerseys.com\/it\/wp-json\/wp\/v2\/product_tag?post=3665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}